{"id":846,"date":"2021-07-19T14:37:02","date_gmt":"2021-07-19T05:37:02","guid":{"rendered":"https:\/\/waseika.com\/us\/?page_id=846"},"modified":"2024-08-02T14:30:43","modified_gmt":"2024-08-02T05:30:43","slug":"sample_request","status":"publish","type":"page","link":"https:\/\/waseika.com\/us\/sample_request\/","title":{"rendered":"Request for sample purchase"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-form.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-846","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/waseika.com\/us\/sample_request\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"ja_JP\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Seika Corporation |\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Request for sample purchase | Seika Corporation\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/waseika.com\/us\/sample_request\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-07-19T05:37:02+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-08-02T05:30:43+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Request for sample purchase | Seika Corporation\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/waseika.com\\\/us\\\/sample_request\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/waseika.com\\\/us#listItem\",\"position\":1,\"name\":\"\\u30db\\u30fc\\u30e0\",\"item\":\"https:\\\/\\\/waseika.com\\\/us\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/waseika.com\\\/us\\\/sample_request\\\/#listItem\",\"name\":\"Request for sample purchase\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/waseika.com\\\/us\\\/sample_request\\\/#listItem\",\"position\":2,\"name\":\"Request for sample purchase\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/waseika.com\\\/us#listItem\",\"name\":\"\\u30db\\u30fc\\u30e0\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/waseika.com\\\/us\\\/#organization\",\"name\":\"Seika Corporation\",\"url\":\"https:\\\/\\\/waseika.com\\\/us\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/waseika.com\\\/us\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/03\\\/seika-logo-english.png\",\"@id\":\"https:\\\/\\\/waseika.com\\\/us\\\/sample_request\\\/#organizationLogo\",\"width\":831,\"height\":831},\"image\":{\"@id\":\"https:\\\/\\\/waseika.com\\\/us\\\/sample_request\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/waseika.com\\\/us\\\/sample_request\\\/#webpage\",\"url\":\"https:\\\/\\\/waseika.com\\\/us\\\/sample_request\\\/\",\"name\":\"Request for sample purchase | Seika Corporation\",\"inLanguage\":\"ja\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/waseika.com\\\/us\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/waseika.com\\\/us\\\/sample_request\\\/#breadcrumblist\"},\"datePublished\":\"2021-07-19T14:37:02+09:00\",\"dateModified\":\"2024-08-02T14:30:43+09:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/waseika.com\\\/us\\\/#website\",\"url\":\"https:\\\/\\\/waseika.com\\\/us\\\/\",\"name\":\"Seika Corporation\",\"inLanguage\":\"ja\",\"publisher\":{\"@id\":\"https:\\\/\\\/waseika.com\\\/us\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Request for sample purchase | Seika Corporation","description":"","canonical_url":"https:\/\/waseika.com\/us\/sample_request\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/waseika.com\/us\/sample_request\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/waseika.com\/us#listItem","position":1,"name":"\u30db\u30fc\u30e0","item":"https:\/\/waseika.com\/us","nextItem":{"@type":"ListItem","@id":"https:\/\/waseika.com\/us\/sample_request\/#listItem","name":"Request for sample purchase"}},{"@type":"ListItem","@id":"https:\/\/waseika.com\/us\/sample_request\/#listItem","position":2,"name":"Request for sample purchase","previousItem":{"@type":"ListItem","@id":"https:\/\/waseika.com\/us#listItem","name":"\u30db\u30fc\u30e0"}}]},{"@type":"Organization","@id":"https:\/\/waseika.com\/us\/#organization","name":"Seika Corporation","url":"https:\/\/waseika.com\/us\/","logo":{"@type":"ImageObject","url":"https:\/\/waseika.com\/us\/wp-content\/uploads\/sites\/2\/2021\/03\/seika-logo-english.png","@id":"https:\/\/waseika.com\/us\/sample_request\/#organizationLogo","width":831,"height":831},"image":{"@id":"https:\/\/waseika.com\/us\/sample_request\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/waseika.com\/us\/sample_request\/#webpage","url":"https:\/\/waseika.com\/us\/sample_request\/","name":"Request for sample purchase | Seika Corporation","inLanguage":"ja","isPartOf":{"@id":"https:\/\/waseika.com\/us\/#website"},"breadcrumb":{"@id":"https:\/\/waseika.com\/us\/sample_request\/#breadcrumblist"},"datePublished":"2021-07-19T14:37:02+09:00","dateModified":"2024-08-02T14:30:43+09:00"},{"@type":"WebSite","@id":"https:\/\/waseika.com\/us\/#website","url":"https:\/\/waseika.com\/us\/","name":"Seika Corporation","inLanguage":"ja","publisher":{"@id":"https:\/\/waseika.com\/us\/#organization"}}]},"og:locale":"ja_JP","og:site_name":"Seika Corporation |","og:type":"article","og:title":"Request for sample purchase | Seika Corporation","og:url":"https:\/\/waseika.com\/us\/sample_request\/","article:published_time":"2021-07-19T05:37:02+00:00","article:modified_time":"2024-08-02T05:30:43+00:00","twitter:card":"summary_large_image","twitter:title":"Request for sample purchase | Seika Corporation"},"aioseo_meta_data":{"post_id":"846","title":null,"description":null,"keywords":null,"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-07-19 05:37:02","updated":"2026-08-20 02:33:08","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"_links":{"self":[{"href":"https:\/\/waseika.com\/us\/wp-json\/wp\/v2\/pages\/846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/waseika.com\/us\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/waseika.com\/us\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/waseika.com\/us\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/waseika.com\/us\/wp-json\/wp\/v2\/comments?post=846"}],"version-history":[{"count":3,"href":"https:\/\/waseika.com\/us\/wp-json\/wp\/v2\/pages\/846\/revisions"}],"predecessor-version":[{"id":1174,"href":"https:\/\/waseika.com\/us\/wp-json\/wp\/v2\/pages\/846\/revisions\/1174"}],"wp:attachment":[{"href":"https:\/\/waseika.com\/us\/wp-json\/wp\/v2\/media?parent=846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}